<script></script><script></script>{"id":767,"date":"2013-07-29T19:11:54","date_gmt":"2013-07-29T22:11:54","guid":{"rendered":"http:\/\/themes.kadencethemes.com\/virtue-premium-4\/?post_type=portfolio&#038;p=183"},"modified":"2023-06-16T15:31:59","modified_gmt":"2023-06-16T18:31:59","slug":"pecas-moldadas-e-montadas","status":"publish","type":"portfolio","link":"https:\/\/bonplast.com.br\/site\/portfolio\/pecas-moldadas-e-montadas\/","title":{"rendered":"Moldagem de acr\u00edlico e Letras Montadas"},"content":{"rendered":"<h5>Atrav\u00e9s do sistema de <strong>moldagem<\/strong> (aquecimento e press\u00e3o), realizamos diversos trabalhos para atender nosso clientes de comunica\u00e7\u00e3o visual. Assim, \u00e9 poss\u00edvel criar os mais variados logotipos, letras e bolhas personalizados e \u00fanicos. O acr\u00edlico \u00e9 um material vers\u00e1til e nobre que agrega durabilidade e eleg\u00e2ncia aos projetos.<\/h5>\n<h5>Outro m\u00e9todo que utilizamos s\u00e3o as <strong>pe\u00e7as montadas<\/strong> em acr\u00edlico. Algumas formas e letras s\u00e3o confeccionadas utilizado-se de tecnologia laser ou router e depois modeladas manualmente possibilitando servi\u00e7os diferenciados e com profundidades maiores.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Atrav\u00e9s do sistema de moldagem (aquecimento e press\u00e3o), realizamos diversos trabalhos para atender nosso clientes de comunica\u00e7\u00e3o visual. Assim, \u00e9 poss\u00edvel criar os mais variados logotipos, letras e bolhas personalizados e \u00fanicos. O acr\u00edlico \u00e9 um material vers\u00e1til e nobre &hellip; <a href=\"https:\/\/bonplast.com.br\/site\/portfolio\/pecas-moldadas-e-montadas\/\">Conte\u00fado<\/a><\/p>\n","protected":false},"author":1,"featured_media":1474,"menu_order":-2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"kt_blocks_editor_width":""},"portfolio-type":[],"_links":{"self":[{"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/portfolio\/767"}],"collection":[{"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/comments?post=767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/media\/1474"}],"wp:attachment":[{"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/media?parent=767"}],"wp:term":[{"taxonomy":"portfolio-type","embeddable":true,"href":"https:\/\/bonplast.com.br\/site\/wp-json\/wp\/v2\/portfolio-type?post=767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}